{"id":25,"count":1,"description":"","link":"http:\/\/www.rememberlayne.com\/blog\/tag\/1987\/","name":"1987","slug":"1987","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/tags\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/posts?tags=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}