{"id":41,"count":1,"description":"","link":"http:\/\/www.rememberlayne.com\/blog\/tag\/charlie-parker\/","name":"Charlie Parker","slug":"charlie-parker","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/tags\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/posts?tags=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}