{"id":43,"count":1,"description":"","link":"http:\/\/www.rememberlayne.com\/blog\/tag\/consequences\/","name":"consequences","slug":"consequences","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/tags\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.rememberlayne.com\/blog\/wp-json\/wp\/v2\/posts?tags=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}